{"id":36,"count":9,"description":"","link":"https:\/\/vapesaler.com\/de\/brands\/bangking","name":"BANGKING","slug":"bangking","taxonomy":"product_brand","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/vapesaler.com\/de\/wp-json\/wp\/v2\/product_brand\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vapesaler.com\/de\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/vapesaler.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/vapesaler.com\/de\/wp-json\/wp\/v2\/product?product_brand=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}